{"id":10049,"date":"2024-11-23T12:59:57","date_gmt":"2024-11-23T12:59:57","guid":{"rendered":"https:\/\/studiofifty.premiumthemes.in\/?page_id=10049"},"modified":"2026-02-07T05:12:12","modified_gmt":"2026-02-07T05:12:12","slug":"main-home","status":"publish","type":"page","link":"https:\/\/bandishstudios.com\/landing\/","title":{"rendered":"Main Home"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"10049\" class=\"elementor elementor-10049\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fa01999 elementor-hidden-desktop elementor-hidden-tablet e-flex e-con-boxed mk-enable-fade-animation-none mk-sticky-column-false mk-sticky-column-disable-tablet e-con e-parent\" data-id=\"fa01999\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;mk-animation-effect&quot;:&quot;none&quot;,&quot;mk_ext_is_sticky&quot;:&quot;false&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cad6331 elementor-widget-mobile__width-initial mk-enable-fade-animation-none elementor-widget elementor-widget-image\" data-id=\"cad6331\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mk-animation-effect&quot;:&quot;none&quot;,&quot;mk_ext_is_infinite&quot;:&quot;false&quot;,&quot;mk_ext_is_scrollme&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/bandishstudios.com\/landing\/wp-content\/uploads\/2024\/11\/imgi_46_imgi_1_latest-bandish-logo-300x300-1-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-11588\" alt=\"\" srcset=\"https:\/\/bandishstudios.com\/landing\/wp-content\/uploads\/2024\/11\/imgi_46_imgi_1_latest-bandish-logo-300x300-1-150x150.png 150w, https:\/\/bandishstudios.com\/landing\/wp-content\/uploads\/2024\/11\/imgi_46_imgi_1_latest-bandish-logo-300x300-1-105x105.png 105w, https:\/\/bandishstudios.com\/landing\/wp-content\/uploads\/2024\/11\/imgi_46_imgi_1_latest-bandish-logo-300x300-1.png 300w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-995463e e-flex e-con-boxed mk-enable-fade-animation-none mk-sticky-column-false mk-sticky-column-disable-tablet e-con e-parent\" data-id=\"995463e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;mk-animation-effect&quot;:&quot;none&quot;,&quot;mk_ext_is_sticky&quot;:&quot;false&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-ad114c4 e-con-full e-flex mk-enable-fade-animation-none mk-sticky-column-false mk-sticky-column-disable-tablet e-con e-child\" data-id=\"ad114c4\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;mk-animation-effect&quot;:&quot;none&quot;,&quot;mk_ext_is_sticky&quot;:&quot;false&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-3a2baf2 e-con-full e-flex mk-enable-fade-animation-none mk-sticky-column-false mk-sticky-column-disable-tablet e-con e-child\" data-id=\"3a2baf2\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;mk-animation-effect&quot;:&quot;none&quot;,&quot;mk_ext_is_sticky&quot;:&quot;false&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-232acb8 mk-t-animation-text_reveal mk-enable-fade-animation-none elementor-widget elementor-widget-mk_animated_title\" data-id=\"232acb8\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mk_text_animation&quot;:&quot;text_reveal&quot;,&quot;mk_text_animation_editor&quot;:&quot;yes&quot;,&quot;text_delay&quot;:0.4,&quot;text_duration&quot;:1,&quot;text_stagger&quot;:0.02,&quot;text_on_scroll&quot;:&quot;yes&quot;,&quot;mk-animation-effect&quot;:&quot;none&quot;,&quot;mk_ext_is_infinite&quot;:&quot;false&quot;,&quot;mk_ext_is_scrollme&quot;:&quot;false&quot;}\" data-widget_type=\"mk_animated_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"mk--animated-title\">We Create Video Content That Grows Your Brand<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-70a51c1 mk-enable-fade-animation-none elementor-widget elementor-widget-heading\" data-id=\"70a51c1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mk-animation-effect&quot;:&quot;none&quot;,&quot;mk_ext_is_infinite&quot;:&quot;false&quot;,&quot;mk_ext_is_scrollme&quot;:&quot;false&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">From brand films to social ads, we craft stories that connect with your audience and deliver results.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-97b82e9 e-con-full e-flex mk-enable-fade-animation-none mk-sticky-column-false mk-sticky-column-disable-tablet e-con e-child\" data-id=\"97b82e9\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;mk-animation-effect&quot;:&quot;none&quot;,&quot;mk_ext_is_sticky&quot;:&quot;false&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-911f1b4 mk-enable-fade-animation-none elementor-widget elementor-widget-metform\" data-id=\"911f1b4\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mk-animation-effect&quot;:&quot;none&quot;,&quot;mk_ext_is_infinite&quot;:&quot;false&quot;,&quot;mk_ext_is_scrollme&quot;:&quot;false&quot;}\" data-widget_type=\"metform.default\">\n\t\t\t\t\t<div id=\"mf-response-props-id-11722\" data-previous-steps-style=\"\" data-editswitchopen=\"\" data-response_type=\"alert\" data-erroricon=\"fas fa-exclamation-triangle\" data-successicon=\"fas fa-check\" data-messageposition=\"top\" class=\"   mf-scroll-top-no\">\n\t\t<div class=\"formpicker_warper formpicker_warper_editable\" data-metform-formpicker-key=\"11722\" >\n\t\t\t\t\n\t\t\t<div class=\"mf-widget-container\">\n\t\t\t\t\r\n\t\t<div\r\n\t\t\tid=\"metform-wrap-911f1b4-11722\"\r\n\t\t\tclass=\"mf-form-wrapper\"\r\n\t\t\tdata-form-id=\"11722\"\r\n\t\t\tdata-action=\"https:\/\/bandishstudios.com\/landing\/wp-json\/metform\/v1\/entries\/insert\/11722\"\r\n\t\t\tdata-wp-nonce=\"6bd5069f60\"\r\n\t\t\tdata-form-nonce=\"289ace10cd\"\r\n\t\t\tdata-quiz-summery = \"false\"\r\n\t\t\tdata-save-progress = \"false\"\r\n\t\t\tdata-form-type=\"general-form\"\r\n\t\t\tdata-stop-vertical-effect=\"\"\r\n\t\t\t><\/div>\r\n\r\n\r\n\t\t<!----------------------------- \r\n\t\t\t* controls_data : find the the props passed indie of data attribute\r\n\t\t\t* props.SubmitResponseMarkup : contains the markup of error or success message\r\n\t\t\t* https:\/\/developer.mozilla.org\/en-US\/docs\/Web\/JavaScript\/Reference\/Template_literals\r\n\t\t--------------------------- -->\r\n\r\n\t\t\t\t<script type=\"text\/mf\" class=\"mf-template\">\r\n\t\t\tfunction controls_data (value){\r\n\t\t\t\tlet currentWrapper = \"mf-response-props-id-11722\";\r\n\t\t\t\tlet currentEl = document.getElementById(currentWrapper);\r\n\t\t\t\t\r\n\t\t\t\treturn currentEl ? currentEl.dataset[value] : false\r\n\t\t\t}\r\n\r\n\r\n\t\t\tlet is_edit_mode = '' ? true : false;\r\n\t\t\tlet message_position = controls_data('messageposition') || 'top';\r\n\r\n\t\t\t\r\n\t\t\tlet message_successIcon = controls_data('successicon') || '';\r\n\t\t\tlet message_errorIcon = controls_data('erroricon') || '';\r\n\t\t\tlet message_editSwitch = controls_data('editswitchopen') === 'yes' ? true : false;\r\n\t\t\tlet message_proClass = controls_data('editswitchopen') === 'yes' ? 'mf_pro_activated' : '';\r\n\t\t\t\r\n\t\t\tlet is_dummy_markup = is_edit_mode && message_editSwitch ? true : false;\r\n\r\n\t\t\t\r\n\t\t\treturn html`\r\n\t\t\t\t<form\r\n\t\t\t\t\tclassName=\"metform-form-content\"\r\n\t\t\t\t\tref=${parent.formContainerRef}\r\n\t\t\t\t\tonSubmit=${ validation.handleSubmit( parent.handleFormSubmit ) }\r\n\t\t\t\t\r\n\t\t\t\t\t>\r\n\t\t\t\r\n\t\t\t\r\n\t\t\t\t\t${is_dummy_markup ? message_position === 'top' ?  props.ResponseDummyMarkup(message_successIcon, message_proClass) : '' : ''}\r\n\t\t\t\t\t${is_dummy_markup ? ' ' :  message_position === 'top' ? props.SubmitResponseMarkup`${parent}${state}${message_successIcon}${message_errorIcon}${message_proClass}` : ''}\r\n\r\n\t\t\t\t\t<!--------------------------------------------------------\r\n\t\t\t\t\t*** IMPORTANT \/ DANGEROUS ***\r\n\t\t\t\t\t${html``} must be used as in immediate child of \"metform-form-main-wrapper\"\r\n\t\t\t\t\tclass otherwise multistep form will not run at all\r\n\t\t\t\t\t---------------------------------------------------------->\r\n\r\n\t\t\t\t\t<div className=\"metform-form-main-wrapper\" key=${'hide-form-after-submit'} ref=${parent.formRef}>\r\n\t\t\t\t\t${html`\r\n\t\t\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" key=\"2\" data-elementor-id=\"11722\" className=\"elementor elementor-11722\">\n\t\t\t\t<div className=\"elementor-element elementor-element-3ff73b4 e-con-full e-flex mk-enable-fade-animation-none mk-sticky-column-false mk-sticky-column-disable-tablet e-con e-parent\" data-id=\"3ff73b4\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;mk-animation-effect&quot;:&quot;none&quot;,&quot;mk_ext_is_sticky&quot;:&quot;false&quot;}\">\n\t\t<div className=\"elementor-element elementor-element-6f795d05 e-con-full e-flex mk-enable-fade-animation-none mk-sticky-column-false mk-sticky-column-disable-tablet e-con e-child\" data-id=\"6f795d05\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;mk-animation-effect&quot;:&quot;none&quot;,&quot;mk_ext_is_sticky&quot;:&quot;false&quot;}\">\n\t\t\t\t<div className=\"elementor-element elementor-element-1476e765 mk-enable-fade-animation-none elementor-widget elementor-widget-heading\" data-id=\"1476e765\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mk-animation-effect&quot;:&quot;none&quot;,&quot;mk_ext_is_infinite&quot;:&quot;false&quot;,&quot;mk_ext_is_scrollme&quot;:&quot;false&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 className=\"elementor-heading-title elementor-size-default\">Get Free Creative Consultation<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div className=\"elementor-element elementor-element-51fe805a mk-enable-fade-animation-none elementor-widget elementor-widget-heading\" data-id=\"51fe805a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mk-animation-effect&quot;:&quot;none&quot;,&quot;mk_ext_is_infinite&quot;:&quot;false&quot;,&quot;mk_ext_is_scrollme&quot;:&quot;false&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p className=\"elementor-heading-title elementor-size-default\">Share your details. Our team will connect shortly.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div className=\"elementor-element elementor-element-5da36d8e e-grid e-con-full mk-enable-fade-animation-none mk-sticky-column-false mk-sticky-column-disable-tablet e-con e-child\" data-id=\"5da36d8e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;mk-animation-effect&quot;:&quot;none&quot;,&quot;mk_ext_is_sticky&quot;:&quot;false&quot;}\">\n\t\t\t\t<div className=\"elementor-element elementor-element-70598782 mk-enable-fade-animation-none elementor-widget elementor-widget-mf-text\" data-id=\"70598782\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mf_input_name&quot;:&quot;Name&quot;,&quot;mk-animation-effect&quot;:&quot;none&quot;,&quot;mk_ext_is_infinite&quot;:&quot;false&quot;,&quot;mk_ext_is_scrollme&quot;:&quot;false&quot;}\" data-widget_type=\"mf-text.default\">\n\t\t\t\t\t\r\n\t\t<div className=\"mf-input-wrapper\">\r\n\t\t\t\r\n\t\t\t<input\r\n\t\t\t\ttype=\"text\"\r\n\t\t\t\tclassName=\"mf-input mf-conditional-input\"\r\n\t\t\t\tid=\"mf-input-text-70598782\"\r\n\t\t\t\tname=\"Name\"\r\n\t\t\t\tplaceholder=\"${ parent.decodeEntities(`Name`) } \"\r\n\t\t\t\t\t\t\t\t\tonInput=${parent.handleChange}\r\n\t\t\t\t\tonBlur=${parent.handleChange}\r\n\t\t\t\t\taria-invalid=${validation.errors['Name'] ? 'true' : 'false'}\r\n\t\t\t\t\tref=${el =>{\r\n\t\t\t\t\t\t\t\t\t\t\t\tparent.activateValidation({\"message\":\"This field is required.\",\"minLength\":1,\"maxLength\":\"\",\"type\":\"none\",\"required\":true,\"expression\":\"null\"}, el)\r\n\t\t\t\t\t}}\r\n\t\t\t\t\t\t\t\t\/>\r\n\r\n\t\t\t\t\t\t\t<${validation.ErrorMessage}\r\n\t\t\t\t\terrors=${validation.errors}\r\n\t\t\t\t\tname=\"Name\"\r\n\t\t\t\t\tas=${html`<span className=\"mf-error-message\"><\/span>`}\r\n\t\t\t\t\t\/>\r\n\t\t\t\r\n\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div className=\"elementor-element elementor-element-a06d9ee mk-enable-fade-animation-none elementor-widget elementor-widget-mf-telephone\" data-id=\"a06d9ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mf_input_name&quot;:&quot;Phone&quot;,&quot;mk-animation-effect&quot;:&quot;none&quot;,&quot;mk_ext_is_infinite&quot;:&quot;false&quot;,&quot;mk_ext_is_scrollme&quot;:&quot;false&quot;}\" data-widget_type=\"mf-telephone.default\">\n\t\t\t\t\t\n\t\t<div className=\"mf-input-wrapper\">\n\t\t\t\n\t\t\t<input\n\t\t\t\ttype=\"tel\"\n\t\t\t\tclassName=\"mf-input mf-conditional-input\"\n\t\t\t\tid=\"mf-input-telephone-a06d9ee\" \n\t\t\t\tname=\"Phone\"\n\t\t\t\tplaceholder=\"${ parent.decodeEntities(`Phone`) } \"\n\t\t\t\t\t\t\t\t\tonInput=${parent.handleChange}\n\t\t\t\t\taria-invalid=${validation.errors['Phone'] ? 'true' : 'false'}\n\t\t\t\t\tref=${el => parent.activateValidation({\"message\":\"This field is required.\",\"minLength\":1,\"maxLength\":\"\",\"type\":\"none\",\"required\":true,\"expression\":\"null\"}, el)}\n\t\t\t\t\t\t\t\t\/>\n\t\t\t\n\t\t\t\t\t\t\t<${validation.ErrorMessage}\n\t\t\t\t\terrors=${validation.errors}\n\t\t\t\t\tname=\"Phone\"\n\t\t\t\t\tas=${html`<span className=\"mf-error-message\"><\/span>`}\n\t\t\t\t\t\/>\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div className=\"elementor-element elementor-element-5fd1ec38 mk-enable-fade-animation-none elementor-widget elementor-widget-mf-email\" data-id=\"5fd1ec38\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mf_input_name&quot;:&quot;Email&quot;,&quot;mk-animation-effect&quot;:&quot;none&quot;,&quot;mk_ext_is_infinite&quot;:&quot;false&quot;,&quot;mk_ext_is_scrollme&quot;:&quot;false&quot;}\" data-widget_type=\"mf-email.default\">\n\t\t\t\t\t\r\n\t\t<div className=\"mf-input-wrapper\">\r\n\t\t\t\r\n\t\t\t<input \r\n\t\t\t\ttype=\"email\" \r\n\t\t\t\t \r\n\t\t\t\tdefaultValue=\"\" \r\n\t\t\t\tclassName=\"mf-input mf-conditional-input\" \r\n\t\t\t\tid=\"mf-input-email-5fd1ec38\" \r\n\t\t\t\tname=\"Email\" \r\n\t\t\t\tplaceholder=\"${ parent.decodeEntities(`Email`) } \" \r\n\t\t\t\t \r\n\t\t\t\tonBlur=${parent.handleChange} onFocus=${parent.handleChange} aria-invalid=${validation.errors['Email'] ? 'true' : 'false' } \r\n\t\t\t\tref=${el=> parent.activateValidation({\"message\":\"This field is required.\",\"emailMessage\":\"Please enter a valid Email address\",\"minLength\":1,\"maxLength\":\"\",\"type\":\"none\",\"required\":true,\"expression\":\"null\"}, el)}\r\n\t\t\t\t\t\t\t\/>\r\n\r\n\t\t\t\t\t\t<${validation.ErrorMessage} \r\n\t\t\t\terrors=${validation.errors} \r\n\t\t\t\tname=\"Email\" \r\n\t\t\t\tas=${html`<span className=\"mf-error-message\"><\/span>`}\r\n\t\t\t\/>\r\n\t\t\t\r\n\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t<\/div>\n\t\t\t\t<div className=\"elementor-element elementor-element-cc8b1fa mk-enable-fade-animation-none elementor-widget elementor-widget-mf-select\" data-id=\"cc8b1fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mf_input_name&quot;:&quot;Service&quot;,&quot;mf_input_list&quot;:[{&quot;mf_input_option_text&quot;:&quot;360 Marketing&quot;,&quot;mf_input_option_value&quot;:&quot;360 Marketing&quot;,&quot;_id&quot;:&quot;a277049&quot;,&quot;mf_input_option_status&quot;:&quot;&quot;,&quot;mf_input_option_selected&quot;:&quot;&quot;},{&quot;mf_input_option_text&quot;:&quot;Branding&quot;,&quot;mf_input_option_value&quot;:&quot;Branding&quot;,&quot;_id&quot;:&quot;58aba46&quot;,&quot;mf_input_option_status&quot;:&quot;&quot;,&quot;mf_input_option_selected&quot;:&quot;&quot;},{&quot;mf_input_option_text&quot;:&quot;Design&quot;,&quot;mf_input_option_value&quot;:&quot;Design&quot;,&quot;_id&quot;:&quot;1a42b7c&quot;,&quot;mf_input_option_status&quot;:&quot;&quot;,&quot;mf_input_option_selected&quot;:&quot;&quot;},{&quot;mf_input_option_text&quot;:&quot;Digital Marketing&quot;,&quot;mf_input_option_value&quot;:&quot;Digital Marketing&quot;,&quot;_id&quot;:&quot;c40e482&quot;,&quot;mf_input_option_status&quot;:&quot;&quot;,&quot;mf_input_option_selected&quot;:&quot;&quot;},{&quot;mf_input_option_text&quot;:&quot;Equipment Rental&quot;,&quot;mf_input_option_value&quot;:&quot;Equipment Rental&quot;,&quot;_id&quot;:&quot;30584d1&quot;,&quot;mf_input_option_status&quot;:&quot;&quot;,&quot;mf_input_option_selected&quot;:&quot;&quot;},{&quot;mf_input_option_text&quot;:&quot;Post Production&quot;,&quot;mf_input_option_value&quot;:&quot;Post Production&quot;,&quot;_id&quot;:&quot;0eb683f&quot;,&quot;mf_input_option_status&quot;:&quot;&quot;,&quot;mf_input_option_selected&quot;:&quot;&quot;},{&quot;mf_input_option_text&quot;:&quot;Product Photography&quot;,&quot;mf_input_option_value&quot;:&quot;Product Photography&quot;,&quot;_id&quot;:&quot;aaf2632&quot;,&quot;mf_input_option_status&quot;:&quot;&quot;,&quot;mf_input_option_selected&quot;:&quot;&quot;},{&quot;mf_input_option_text&quot;:&quot;Signages&quot;,&quot;mf_input_option_value&quot;:&quot;Signages&quot;,&quot;_id&quot;:&quot;763cc5a&quot;,&quot;mf_input_option_status&quot;:&quot;&quot;,&quot;mf_input_option_selected&quot;:&quot;&quot;},{&quot;mf_input_option_text&quot;:&quot;Social Media&quot;,&quot;mf_input_option_value&quot;:&quot;Social Media&quot;,&quot;_id&quot;:&quot;db98280&quot;,&quot;mf_input_option_status&quot;:&quot;&quot;,&quot;mf_input_option_selected&quot;:&quot;&quot;},{&quot;mf_input_option_text&quot;:&quot;Sync Sound&quot;,&quot;mf_input_option_value&quot;:&quot;Sync Sound&quot;,&quot;_id&quot;:&quot;925c3a7&quot;,&quot;mf_input_option_status&quot;:&quot;&quot;,&quot;mf_input_option_selected&quot;:&quot;&quot;},{&quot;mf_input_option_text&quot;:&quot;Video Production&quot;,&quot;mf_input_option_value&quot;:&quot;value-11&quot;,&quot;_id&quot;:&quot;510a60d&quot;,&quot;mf_input_option_status&quot;:&quot;&quot;,&quot;mf_input_option_selected&quot;:&quot;&quot;},{&quot;mf_input_option_text&quot;:&quot;Website&quot;,&quot;mf_input_option_value&quot;:&quot;Website&quot;,&quot;_id&quot;:&quot;e9d49c2&quot;,&quot;mf_input_option_status&quot;:&quot;&quot;,&quot;mf_input_option_selected&quot;:&quot;&quot;},{&quot;_id&quot;:&quot;d95cff2&quot;,&quot;mf_input_option_text&quot;:&quot;Digital Ads&quot;,&quot;mf_input_option_value&quot;:&quot;Digital Ads&quot;,&quot;mf_input_option_status&quot;:&quot;&quot;,&quot;mf_input_option_selected&quot;:&quot;&quot;},{&quot;_id&quot;:&quot;1343f9b&quot;,&quot;mf_input_option_text&quot;:&quot;AI Video Production&quot;,&quot;mf_input_option_value&quot;:&quot;AI Video Production&quot;,&quot;mf_input_option_status&quot;:&quot;&quot;,&quot;mf_input_option_selected&quot;:&quot;&quot;}],&quot;mk-animation-effect&quot;:&quot;none&quot;,&quot;mk_ext_is_infinite&quot;:&quot;false&quot;,&quot;mk_ext_is_scrollme&quot;:&quot;false&quot;}\" data-widget_type=\"mf-select.default\">\n\t\t\t\t\t\n\t\t\n\t\t<div className=\"mf-input-wrapper\">\n\t\t\t\n            <${props.Select}\n                className=${\"mf-input mf-input-select  \" + ( validation.errors['Service'] ? 'mf-invalid' : '' )}\n                classNamePrefix=\"mf_select\"\n                name=\"Service\"\n                placeholder=\"${ parent.decodeEntities(`Service`) } \"\n                isSearchable=${false}\n                options=${[{\"label\":\"360 Marketing\",\"value\":\"360 Marketing\",\"isDisabled\":false},{\"label\":\"Branding\",\"value\":\"Branding\",\"isDisabled\":false},{\"label\":\"Design\",\"value\":\"Design\",\"isDisabled\":false},{\"label\":\"Digital Marketing\",\"value\":\"Digital Marketing\",\"isDisabled\":false},{\"label\":\"Equipment Rental\",\"value\":\"Equipment Rental\",\"isDisabled\":false},{\"label\":\"Post Production\",\"value\":\"Post Production\",\"isDisabled\":false},{\"label\":\"Product Photography\",\"value\":\"Product Photography\",\"isDisabled\":false},{\"label\":\"Signages\",\"value\":\"Signages\",\"isDisabled\":false},{\"label\":\"Social Media\",\"value\":\"Social Media\",\"isDisabled\":false},{\"label\":\"Sync Sound\",\"value\":\"Sync Sound\",\"isDisabled\":false},{\"label\":\"Video Production\",\"value\":\"value-11\",\"isDisabled\":false},{\"label\":\"Website\",\"value\":\"Website\",\"isDisabled\":false},{\"label\":\"Digital Ads\",\"value\":\"Digital Ads\",\"isDisabled\":false},{\"label\":\"AI Video Production\",\"value\":\"AI Video Production\",\"isDisabled\":false}]}\n                value=${parent.getValue(\"Service\") ? [{\"label\":\"360 Marketing\",\"value\":\"360 Marketing\",\"isDisabled\":false},{\"label\":\"Branding\",\"value\":\"Branding\",\"isDisabled\":false},{\"label\":\"Design\",\"value\":\"Design\",\"isDisabled\":false},{\"label\":\"Digital Marketing\",\"value\":\"Digital Marketing\",\"isDisabled\":false},{\"label\":\"Equipment Rental\",\"value\":\"Equipment Rental\",\"isDisabled\":false},{\"label\":\"Post Production\",\"value\":\"Post Production\",\"isDisabled\":false},{\"label\":\"Product Photography\",\"value\":\"Product Photography\",\"isDisabled\":false},{\"label\":\"Signages\",\"value\":\"Signages\",\"isDisabled\":false},{\"label\":\"Social Media\",\"value\":\"Social Media\",\"isDisabled\":false},{\"label\":\"Sync Sound\",\"value\":\"Sync Sound\",\"isDisabled\":false},{\"label\":\"Video Production\",\"value\":\"value-11\",\"isDisabled\":false},{\"label\":\"Website\",\"value\":\"Website\",\"isDisabled\":false},{\"label\":\"Digital Ads\",\"value\":\"Digital Ads\",\"isDisabled\":false},{\"label\":\"AI Video Production\",\"value\":\"AI Video Production\",\"isDisabled\":false}].filter(item => item.value === parent.getValue(\"Service\"))[0] : []}\n                onChange=${(e)=> parent.handleSelect(e, \"Service\")}\n                ref=${() => {\n\t\t\t\t                    register({ name: \"Service\" }, parent.activateValidation({\"message\":\"This field is required.\",\"minLength\":1,\"maxLength\":\"\",\"type\":\"none\",\"required\":false}));\n                    if ( parent.getValue(\"Service\") === '' && false ) {\n\t\t\t\t    parent.setValue( 'Service', '', true );\n                        parent.handleChange({\n                            target: {\n                                name: 'Service',\n                                value: ''\n                            }\n                        });\n                    }\n                }}\n                \/>\n\n            \t\t\t\t<${validation.ErrorMessage}\n\t\t\t\t\terrors=${validation.errors}\n\t\t\t\t\tname=\"Service\"\n\t\t\t\t\tas=${html`<span className=\"mf-error-message\"><\/span>`}\n\t\t\t\t\t\/>\n\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div className=\"elementor-element elementor-element-1f8d3f6f elementor-widget__width-auto mk-enable-fade-animation-none elementor-widget elementor-widget-mf-button\" data-id=\"1f8d3f6f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mk-animation-effect&quot;:&quot;none&quot;,&quot;mk_ext_is_infinite&quot;:&quot;false&quot;,&quot;mk_ext_is_scrollme&quot;:&quot;false&quot;}\" data-widget_type=\"mf-button.default\">\n\t\t\t\t\t\t\t<div className=\"mf-btn-wraper mf-conditional-input\" data-mf-form-conditional-logic-requirement=\"\">\r\n\t\t\t\t\t\t\t<button type=\"submit\" className=\"metform-btn metform-submit-btn \" id=\"\">\r\n\t\t\t\t\t<span>${ parent.decodeEntities(`Send Request`) } <\/span>\r\n\t\t\t\t<\/button>\r\n\t\t\t        <\/div>\r\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t`}\r\n\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t${is_dummy_markup ? message_position === 'bottom' ? props.ResponseDummyMarkup(message_successIcon, message_proClass) : '' : ''}\r\n\t\t\t\t\t${is_dummy_markup ? ' ' : message_position === 'bottom' ? props.SubmitResponseMarkup`${parent}${state}${message_successIcon}${message_errorIcon}${message_proClass}` : ''}\r\n\t\t\t\t\r\n\t\t\t\t<\/form>\r\n\t\t\t`\r\n\t\t<\/script>\r\n\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2552428f e-flex e-con-boxed mk-enable-fade-animation-none mk-sticky-column-false mk-sticky-column-disable-tablet e-con e-parent\" data-id=\"2552428f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_top&quot;:&quot;opacity-tilt&quot;,&quot;mk-animation-effect&quot;:&quot;none&quot;,&quot;mk_ext_is_sticky&quot;:&quot;false&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-shape elementor-shape-top\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 2600 131.1\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M0 0L2600 0 2600 69.1 0 0z\"\/>\n\t<path class=\"elementor-shape-fill\" style=\"opacity:0.5\" d=\"M0 0L2600 0 2600 69.1 0 69.1z\"\/>\n\t<path class=\"elementor-shape-fill\" style=\"opacity:0.25\" d=\"M2600 0L0 0 0 130.1 2600 69.1z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-535bec5 mk-enable-fade-animation-none elementor-widget elementor-widget-video\" data-id=\"535bec5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/BrfY50XYeq0&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;play_on_mobile&quot;:&quot;yes&quot;,&quot;mute&quot;:&quot;yes&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;,&quot;mk-animation-effect&quot;:&quot;none&quot;,&quot;mk_ext_is_infinite&quot;:&quot;false&quot;,&quot;mk_ext_is_scrollme&quot;:&quot;false&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-45c17707 e-flex e-con-boxed mk-enable-fade-animation-none mk-sticky-column-false mk-sticky-column-disable-tablet e-con e-parent\" data-id=\"45c17707\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;mk-animation-effect&quot;:&quot;none&quot;,&quot;mk_ext_is_sticky&quot;:&quot;false&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-252b9347 e-con-full e-flex mk-enable-fade-animation-none mk-sticky-column-false mk-sticky-column-disable-tablet e-con e-child\" data-id=\"252b9347\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;mk-animation-effect&quot;:&quot;none&quot;,&quot;mk_ext_is_sticky&quot;:&quot;false&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7cc04a04 mk-enable-fade-animation-fade mk-title-align--center mk-title-align--mobile-center elementor-widget elementor-widget-mk_title\" data-id=\"7cc04a04\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mk-animation-effect&quot;:&quot;fade&quot;,&quot;fade-from&quot;:&quot;right&quot;,&quot;delay&quot;:0.15,&quot;on-scroll&quot;:1,&quot;data-duration&quot;:1.5,&quot;ease&quot;:&quot;power2.out&quot;,&quot;fade-offset&quot;:50,&quot;mk_ext_is_infinite&quot;:&quot;false&quot;,&quot;mk_ext_is_scrollme&quot;:&quot;false&quot;}\" data-widget_type=\"mk_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"mk-title mk-title-default mk-scroll--load\"><h4 class=\"mk-title-heading swm-hide-none\"><span>Here's what we have been creating!<\/span><\/h4><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-625424fd e-flex e-con-boxed mk-enable-fade-animation-none mk-sticky-column-false mk-sticky-column-disable-tablet e-con e-parent\" data-id=\"625424fd\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;mk-animation-effect&quot;:&quot;none&quot;,&quot;mk_ext_is_sticky&quot;:&quot;false&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-33b0de0f e-con-full e-flex mk-enable-fade-animation-none mk-sticky-column-false mk-sticky-column-disable-tablet e-con e-child\" data-id=\"33b0de0f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;mk-animation-effect&quot;:&quot;none&quot;,&quot;mk_ext_is_sticky&quot;:&quot;false&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-40878fc2 elementor-widget__width-initial mk-t-animation-char elementor-widget-tablet__width-inherit mk-enable-fade-animation-none elementor-widget elementor-widget-mk_animated_title\" data-id=\"40878fc2\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mk_text_animation&quot;:&quot;char&quot;,&quot;text_delay&quot;:0.15,&quot;text_duration&quot;:1,&quot;text_stagger&quot;:0.02,&quot;text_on_scroll&quot;:&quot;yes&quot;,&quot;text_translate_x&quot;:20,&quot;text_translate_y&quot;:0,&quot;mk-animation-effect&quot;:&quot;none&quot;,&quot;mk_ext_is_infinite&quot;:&quot;false&quot;,&quot;mk_ext_is_scrollme&quot;:&quot;false&quot;}\" data-widget_type=\"mk_animated_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"mk--animated-title\">At Bandish, we believe every idea deserves a powerful story.<br>\nFrom cinematic brand films to AI-powered content, we blend creativity, craft, and\ncutting-edge tech to make brands unforgettable. <br><br>\n\nWe\u2019re not just another agency we\u2019re your creative partners in turning imagination into\nimpact. <br><br>\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-188df232 mk-enable-fade-animation-fade elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"188df232\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;delay&quot;:0.3,&quot;fade-from&quot;:&quot;right&quot;,&quot;mk_ext_is_infinite&quot;:&quot;true&quot;,&quot;mk_ext_infinite_easing&quot;:&quot;0.250, 0.100, 0.250, 1.000&quot;,&quot;mk-animation-effect&quot;:&quot;fade&quot;,&quot;on-scroll&quot;:1,&quot;data-duration&quot;:1.5,&quot;ease&quot;:&quot;power2.out&quot;,&quot;fade-offset&quot;:50,&quot;mk_ext_infinite_animation&quot;:&quot;if_bounce&quot;,&quot;mk_ext_infinite_duration&quot;:4,&quot;mk_ext_is_scrollme&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"408\" height=\"612\" src=\"https:\/\/bandishstudios.com\/landing\/wp-content\/uploads\/2025\/09\/ChatGPT_Image_Sep_24__2025__12_59_52_PM-removebg-preview.png\" class=\"attachment-full size-full wp-image-11660\" alt=\"\" srcset=\"https:\/\/bandishstudios.com\/landing\/wp-content\/uploads\/2025\/09\/ChatGPT_Image_Sep_24__2025__12_59_52_PM-removebg-preview.png 408w, https:\/\/bandishstudios.com\/landing\/wp-content\/uploads\/2025\/09\/ChatGPT_Image_Sep_24__2025__12_59_52_PM-removebg-preview-200x300.png 200w\" sizes=\"(max-width: 408px) 100vw, 408px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4aa08d9e e-con-full mk-enable-fade-animation-fade e-flex mk-sticky-column-false mk-sticky-column-disable-tablet e-con e-child\" data-id=\"4aa08d9e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;mk-animation-effect&quot;:&quot;fade&quot;,&quot;fade-from&quot;:&quot;right&quot;,&quot;delay&quot;:0.15,&quot;on-scroll&quot;:1,&quot;data-duration&quot;:1.5,&quot;ease&quot;:&quot;power2.out&quot;,&quot;fade-offset&quot;:50,&quot;mk_ext_is_sticky&quot;:&quot;false&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-48032ceb mk-enable-fade-animation-none elementor-widget elementor-widget-mk_image_accordion\" data-id=\"48032ceb\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mk-animation-effect&quot;:&quot;none&quot;,&quot;mk_ext_is_infinite&quot;:&quot;false&quot;,&quot;mk_ext_is_scrollme&quot;:&quot;false&quot;}\" data-widget_type=\"mk_image_accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"mk-image-accordion mk-image-accordion-horizontal\" data-grow=\"4\"><div class=\"mk-image-accordion-item active\">\r\n                            <div class=\"mk-image-accordion-item-inner\" style=background-image:url(https:\/\/bandishstudios.com\/landing\/wp-content\/uploads\/2025\/10\/films-1.png)>\r\n                            <\/div>\r\n                        <\/div><div class=\"mk-image-accordion-item \">\r\n                            <div class=\"mk-image-accordion-item-inner\" style=background-image:url(https:\/\/bandishstudios.com\/landing\/wp-content\/uploads\/2025\/10\/branding-1.png)>\r\n                            <\/div>\r\n                        <\/div><div class=\"mk-image-accordion-item \">\r\n                            <div class=\"mk-image-accordion-item-inner\" style=background-image:url(https:\/\/bandishstudios.com\/landing\/wp-content\/uploads\/2025\/10\/ads-1.png)>\r\n                            <\/div>\r\n                        <\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-49e8e1c e-flex e-con-boxed mk-enable-fade-animation-none mk-sticky-column-false mk-sticky-column-disable-tablet e-con e-parent\" data-id=\"49e8e1c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;mk-animation-effect&quot;:&quot;none&quot;,&quot;mk_ext_is_sticky&quot;:&quot;false&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-e40e1fd e-con-full e-flex mk-enable-fade-animation-none mk-sticky-column-false mk-sticky-column-disable-tablet e-con e-child\" data-id=\"e40e1fd\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;mk-animation-effect&quot;:&quot;none&quot;,&quot;mk_ext_is_sticky&quot;:&quot;false&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c4fdd4d mk-enable-fade-animation-fade mk-title-align--center elementor-widget elementor-widget-mk_title\" data-id=\"c4fdd4d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mk-animation-effect&quot;:&quot;fade&quot;,&quot;fade-from&quot;:&quot;right&quot;,&quot;delay&quot;:0.15,&quot;on-scroll&quot;:1,&quot;data-duration&quot;:1.5,&quot;ease&quot;:&quot;power2.out&quot;,&quot;fade-offset&quot;:50,&quot;mk_ext_is_infinite&quot;:&quot;false&quot;,&quot;mk_ext_is_scrollme&quot;:&quot;false&quot;}\" data-widget_type=\"mk_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"mk-title mk-title-default\"><div class=\"mk-title-heading swm-hide-none\"><span>Our Clients<\/span><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fa754a5 e-con-full e-flex mk-enable-fade-animation-none mk-sticky-column-false mk-sticky-column-disable-tablet e-con e-parent\" data-id=\"fa754a5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;mk-animation-effect&quot;:&quot;none&quot;,&quot;mk_ext_is_sticky&quot;:&quot;false&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-4001975 e-con-full e-flex mk-enable-fade-animation-none mk-sticky-column-false mk-sticky-column-disable-tablet e-con e-child\" data-id=\"4001975\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;mk-animation-effect&quot;:&quot;none&quot;,&quot;mk_ext_is_sticky&quot;:&quot;false&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a306f19 mk-enable-fade-animation-none elementor-widget elementor-widget-image-carousel\" data-id=\"a306f19\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;6&quot;,&quot;slides_to_show_mobile&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;none&quot;,&quot;autoplay_speed&quot;:1000,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:32,&quot;sizes&quot;:[]},&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;mk-animation-effect&quot;:&quot;none&quot;,&quot;mk_ext_is_infinite&quot;:&quot;false&quot;,&quot;mk_ext_is_scrollme&quot;:&quot;false&quot;}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Image Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/bandishstudios.com\/landing\/wp-content\/uploads\/2025\/12\/Asset-77.webp\" alt=\"Asset-77\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/bandishstudios.com\/landing\/wp-content\/uploads\/2025\/12\/Asset-75.webp\" alt=\"Asset-75\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/bandishstudios.com\/landing\/wp-content\/uploads\/2025\/12\/Asset-67.webp\" alt=\"Asset-67\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 of 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/bandishstudios.com\/landing\/wp-content\/uploads\/2025\/12\/Asset-57.webp\" alt=\"Asset-57\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 of 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/bandishstudios.com\/landing\/wp-content\/uploads\/2025\/12\/Asset-59.webp\" alt=\"Asset-59\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 of 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/bandishstudios.com\/landing\/wp-content\/uploads\/2025\/12\/Asset-39.webp\" alt=\"Asset-39\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 of 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/bandishstudios.com\/landing\/wp-content\/uploads\/2025\/12\/Asset-76.webp\" alt=\"Asset-76\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 of 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/bandishstudios.com\/landing\/wp-content\/uploads\/2025\/12\/Asset-37.webp\" alt=\"Asset-37\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 of 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/bandishstudios.com\/landing\/wp-content\/uploads\/2025\/12\/Asset-21.webp\" alt=\"Asset-21\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 of 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/bandishstudios.com\/landing\/wp-content\/uploads\/2025\/12\/Asset-23.webp\" alt=\"Asset-23\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"11 of 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/bandishstudios.com\/landing\/wp-content\/uploads\/2026\/01\/SKODA-3D-Standard-Logo_sRGB-e1478246875778-3-300x296.webp\" alt=\"SKODA-3D-Standard-Logo_sRGB-e1478246875778 (3)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"12 of 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/bandishstudios.com\/landing\/wp-content\/uploads\/2026\/01\/INS-Shivaji_001-300x300.webp\" alt=\"INS Shivaji_001\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7f180a46 e-flex e-con-boxed mk-enable-fade-animation-none mk-sticky-column-false mk-sticky-column-disable-tablet e-con e-parent\" data-id=\"7f180a46\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;mk-animation-effect&quot;:&quot;none&quot;,&quot;mk_ext_is_sticky&quot;:&quot;false&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-66e8b4cf e-con-full e-flex mk-enable-fade-animation-none mk-sticky-column-false mk-sticky-column-disable-tablet e-con e-child\" data-id=\"66e8b4cf\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;mk-animation-effect&quot;:&quot;none&quot;,&quot;mk_ext_is_sticky&quot;:&quot;false&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-63d4b604 mk-enable-fade-animation-fade mk-t-animation-none elementor-widget elementor-widget-mk_animated_title\" data-id=\"63d4b604\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mk-animation-effect&quot;:&quot;fade&quot;,&quot;fade-from&quot;:&quot;right&quot;,&quot;mk_text_animation&quot;:&quot;none&quot;,&quot;delay&quot;:0.15,&quot;on-scroll&quot;:1,&quot;data-duration&quot;:1.5,&quot;ease&quot;:&quot;power2.out&quot;,&quot;fade-offset&quot;:50,&quot;mk_ext_is_infinite&quot;:&quot;false&quot;,&quot;mk_ext_is_scrollme&quot;:&quot;false&quot;}\" data-widget_type=\"mk_animated_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"mk--animated-title\">What<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-63780ba9 e-con-full e-flex mk-enable-fade-animation-none mk-sticky-column-false mk-sticky-column-disable-tablet e-con e-child\" data-id=\"63780ba9\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;mk-animation-effect&quot;:&quot;none&quot;,&quot;mk_ext_is_sticky&quot;:&quot;false&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-67389f2d e-con-full e-flex mk-enable-fade-animation-none mk-sticky-column-false mk-sticky-column-disable-tablet e-con e-child\" data-id=\"67389f2d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;mk-animation-effect&quot;:&quot;none&quot;,&quot;mk_ext_is_sticky&quot;:&quot;false&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5aa807c1 mk-enable-fade-animation-fade mk-title-align--left elementor-widget elementor-widget-mk_title\" data-id=\"5aa807c1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mk-animation-effect&quot;:&quot;fade&quot;,&quot;fade-from&quot;:&quot;right&quot;,&quot;delay&quot;:0.15,&quot;on-scroll&quot;:1,&quot;data-duration&quot;:1.5,&quot;ease&quot;:&quot;power2.out&quot;,&quot;fade-offset&quot;:50,&quot;mk_ext_is_infinite&quot;:&quot;false&quot;,&quot;mk_ext_is_scrollme&quot;:&quot;false&quot;}\" data-widget_type=\"mk_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"mk-title mk-title-default\"><div class=\"mk-title-heading swm-hide-none\"><span>Can<\/span><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-32f79ab mk-enable-fade-animation-fade mk-title-align--left elementor-widget elementor-widget-mk_title\" data-id=\"32f79ab\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mk-animation-effect&quot;:&quot;fade&quot;,&quot;fade-from&quot;:&quot;right&quot;,&quot;delay&quot;:0.15,&quot;on-scroll&quot;:1,&quot;data-duration&quot;:1.5,&quot;ease&quot;:&quot;power2.out&quot;,&quot;fade-offset&quot;:50,&quot;mk_ext_is_infinite&quot;:&quot;false&quot;,&quot;mk_ext_is_scrollme&quot;:&quot;false&quot;}\" data-widget_type=\"mk_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"mk-title mk-title-default\"><div class=\"mk-title-heading swm-hide-none\"><span>We<\/span><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1a66d3c7 mk-enable-fade-animation-fade elementor-widget-tablet__width-initial elementor-widget elementor-widget-mk_title\" data-id=\"1a66d3c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mk-animation-effect&quot;:&quot;fade&quot;,&quot;fade-from&quot;:&quot;right&quot;,&quot;delay&quot;:0.3,&quot;on-scroll&quot;:1,&quot;data-duration&quot;:1.5,&quot;ease&quot;:&quot;power2.out&quot;,&quot;fade-offset&quot;:50,&quot;mk_ext_is_infinite&quot;:&quot;false&quot;,&quot;mk_ext_is_scrollme&quot;:&quot;false&quot;}\" data-widget_type=\"mk_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"mk-title mk-title-default\"><h2 class=\"mk-title-heading swm-hide-none\"><span>Do For You?<\/span><\/h2><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7520f76 e-grid e-con-boxed mk-enable-fade-animation-none mk-sticky-column-false mk-sticky-column-disable-tablet e-con e-parent\" data-id=\"7520f76\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;mk-animation-effect&quot;:&quot;none&quot;,&quot;mk_ext_is_sticky&quot;:&quot;false&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<a class=\"elementor-element elementor-element-c3e9535 e-con-full e-flex mk-enable-fade-animation-none mk-sticky-column-false mk-sticky-column-disable-tablet e-con e-child\" data-id=\"c3e9535\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;mk-animation-effect&quot;:&quot;none&quot;,&quot;mk_ext_is_sticky&quot;:&quot;false&quot;}\" href=\"https:\/\/bandishstudios.com\/services\/\">\n\t\t\t\t<div class=\"elementor-element elementor-element-443bbb8 mk-enable-fade-animation-none elementor-widget elementor-widget-image\" data-id=\"443bbb8\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mk-animation-effect&quot;:&quot;none&quot;,&quot;mk_ext_is_infinite&quot;:&quot;false&quot;,&quot;mk_ext_is_scrollme&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/bandishstudios.com\/landing\/wp-content\/uploads\/2025\/10\/films-1-1024x1024.png\" class=\"attachment-large size-large wp-image-11695\" alt=\"\" srcset=\"https:\/\/bandishstudios.com\/landing\/wp-content\/uploads\/2025\/10\/films-1-1024x1024.png 1024w, https:\/\/bandishstudios.com\/landing\/wp-content\/uploads\/2025\/10\/films-1-300x300.png 300w, https:\/\/bandishstudios.com\/landing\/wp-content\/uploads\/2025\/10\/films-1-150x150.png 150w, https:\/\/bandishstudios.com\/landing\/wp-content\/uploads\/2025\/10\/films-1-768x768.png 768w, https:\/\/bandishstudios.com\/landing\/wp-content\/uploads\/2025\/10\/films-1-105x105.png 105w, https:\/\/bandishstudios.com\/landing\/wp-content\/uploads\/2025\/10\/films-1-750x750.png 750w, https:\/\/bandishstudios.com\/landing\/wp-content\/uploads\/2025\/10\/films-1.png 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c596bc2 mk-enable-fade-animation-none elementor-widget elementor-widget-heading\" data-id=\"c596bc2\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mk-animation-effect&quot;:&quot;none&quot;,&quot;mk_ext_is_infinite&quot;:&quot;false&quot;,&quot;mk_ext_is_scrollme&quot;:&quot;false&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Films<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<a class=\"elementor-element elementor-element-2185940 e-con-full e-flex mk-enable-fade-animation-none mk-sticky-column-false mk-sticky-column-disable-tablet e-con e-child\" data-id=\"2185940\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;mk-animation-effect&quot;:&quot;none&quot;,&quot;mk_ext_is_sticky&quot;:&quot;false&quot;}\" href=\"https:\/\/bandishstudios.com\/services-ads\/\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e66c11a mk-enable-fade-animation-none elementor-widget elementor-widget-image\" data-id=\"e66c11a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mk-animation-effect&quot;:&quot;none&quot;,&quot;mk_ext_is_infinite&quot;:&quot;false&quot;,&quot;mk_ext_is_scrollme&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/bandishstudios.com\/landing\/wp-content\/uploads\/2025\/10\/ads-1-1024x1024.png\" class=\"attachment-large size-large wp-image-11693\" alt=\"\" srcset=\"https:\/\/bandishstudios.com\/landing\/wp-content\/uploads\/2025\/10\/ads-1-1024x1024.png 1024w, https:\/\/bandishstudios.com\/landing\/wp-content\/uploads\/2025\/10\/ads-1-300x300.png 300w, https:\/\/bandishstudios.com\/landing\/wp-content\/uploads\/2025\/10\/ads-1-150x150.png 150w, https:\/\/bandishstudios.com\/landing\/wp-content\/uploads\/2025\/10\/ads-1-768x768.png 768w, https:\/\/bandishstudios.com\/landing\/wp-content\/uploads\/2025\/10\/ads-1-105x105.png 105w, https:\/\/bandishstudios.com\/landing\/wp-content\/uploads\/2025\/10\/ads-1-750x750.png 750w, https:\/\/bandishstudios.com\/landing\/wp-content\/uploads\/2025\/10\/ads-1.png 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ddfc9c3 mk-enable-fade-animation-none elementor-widget elementor-widget-heading\" data-id=\"ddfc9c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mk-animation-effect&quot;:&quot;none&quot;,&quot;mk_ext_is_infinite&quot;:&quot;false&quot;,&quot;mk_ext_is_scrollme&quot;:&quot;false&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ads<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<a class=\"elementor-element elementor-element-d1ca0bd e-con-full e-flex mk-enable-fade-animation-none mk-sticky-column-false mk-sticky-column-disable-tablet e-con e-child\" data-id=\"d1ca0bd\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;mk-animation-effect&quot;:&quot;none&quot;,&quot;mk_ext_is_sticky&quot;:&quot;false&quot;}\" href=\"https:\/\/bandishstudios.com\/services-branding\/\">\n\t\t\t\t<div class=\"elementor-element elementor-element-80c326d mk-enable-fade-animation-none elementor-widget elementor-widget-image\" data-id=\"80c326d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mk-animation-effect&quot;:&quot;none&quot;,&quot;mk_ext_is_infinite&quot;:&quot;false&quot;,&quot;mk_ext_is_scrollme&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/bandishstudios.com\/landing\/wp-content\/uploads\/2025\/10\/branding-1-1024x1024.png\" class=\"attachment-large size-large wp-image-11694\" alt=\"\" srcset=\"https:\/\/bandishstudios.com\/landing\/wp-content\/uploads\/2025\/10\/branding-1-1024x1024.png 1024w, https:\/\/bandishstudios.com\/landing\/wp-content\/uploads\/2025\/10\/branding-1-300x300.png 300w, https:\/\/bandishstudios.com\/landing\/wp-content\/uploads\/2025\/10\/branding-1-150x150.png 150w, https:\/\/bandishstudios.com\/landing\/wp-content\/uploads\/2025\/10\/branding-1-768x768.png 768w, https:\/\/bandishstudios.com\/landing\/wp-content\/uploads\/2025\/10\/branding-1-105x105.png 105w, https:\/\/bandishstudios.com\/landing\/wp-content\/uploads\/2025\/10\/branding-1-750x750.png 750w, https:\/\/bandishstudios.com\/landing\/wp-content\/uploads\/2025\/10\/branding-1.png 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-acfe77f mk-enable-fade-animation-none elementor-widget elementor-widget-heading\" data-id=\"acfe77f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mk-animation-effect&quot;:&quot;none&quot;,&quot;mk_ext_is_infinite&quot;:&quot;false&quot;,&quot;mk_ext_is_scrollme&quot;:&quot;false&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Branding<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-810f589 e-flex e-con-boxed mk-enable-fade-animation-none mk-sticky-column-false mk-sticky-column-disable-tablet e-con e-parent\" data-id=\"810f589\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;mk-animation-effect&quot;:&quot;none&quot;,&quot;mk_ext_is_sticky&quot;:&quot;false&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-45def56 e-con-full e-flex mk-enable-fade-animation-none mk-sticky-column-false mk-sticky-column-disable-tablet e-con e-child\" data-id=\"45def56\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;mk-animation-effect&quot;:&quot;none&quot;,&quot;mk_ext_is_sticky&quot;:&quot;false&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-53ad0d4 mk-enable-fade-animation-none elementor-widget elementor-widget-metform\" data-id=\"53ad0d4\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mk-animation-effect&quot;:&quot;none&quot;,&quot;mk_ext_is_infinite&quot;:&quot;false&quot;,&quot;mk_ext_is_scrollme&quot;:&quot;false&quot;}\" data-widget_type=\"metform.default\">\n\t\t\t\t\t<div id=\"mf-response-props-id-11722\" data-previous-steps-style=\"\" data-editswitchopen=\"\" data-response_type=\"alert\" data-erroricon=\"fas fa-exclamation-triangle\" data-successicon=\"fas fa-check\" data-messageposition=\"top\" class=\"   mf-scroll-top-no\">\n\t\t<div class=\"formpicker_warper formpicker_warper_editable\" data-metform-formpicker-key=\"11722\" >\n\t\t\t\t\n\t\t\t<div class=\"mf-widget-container\">\n\t\t\t\t\r\n\t\t<div\r\n\t\t\tid=\"metform-wrap-53ad0d4-11722\"\r\n\t\t\tclass=\"mf-form-wrapper\"\r\n\t\t\tdata-form-id=\"11722\"\r\n\t\t\tdata-action=\"https:\/\/bandishstudios.com\/landing\/wp-json\/metform\/v1\/entries\/insert\/11722\"\r\n\t\t\tdata-wp-nonce=\"6bd5069f60\"\r\n\t\t\tdata-form-nonce=\"289ace10cd\"\r\n\t\t\tdata-quiz-summery = \"false\"\r\n\t\t\tdata-save-progress = \"false\"\r\n\t\t\tdata-form-type=\"general-form\"\r\n\t\t\tdata-stop-vertical-effect=\"\"\r\n\t\t\t><\/div>\r\n\r\n\r\n\t\t<!----------------------------- \r\n\t\t\t* controls_data : find the the props passed indie of data attribute\r\n\t\t\t* props.SubmitResponseMarkup : contains the markup of error or success message\r\n\t\t\t* https:\/\/developer.mozilla.org\/en-US\/docs\/Web\/JavaScript\/Reference\/Template_literals\r\n\t\t--------------------------- -->\r\n\r\n\t\t\t\t<script type=\"text\/mf\" class=\"mf-template\">\r\n\t\t\tfunction controls_data (value){\r\n\t\t\t\tlet currentWrapper = \"mf-response-props-id-11722\";\r\n\t\t\t\tlet currentEl = document.getElementById(currentWrapper);\r\n\t\t\t\t\r\n\t\t\t\treturn currentEl ? currentEl.dataset[value] : false\r\n\t\t\t}\r\n\r\n\r\n\t\t\tlet is_edit_mode = '' ? true : false;\r\n\t\t\tlet message_position = controls_data('messageposition') || 'top';\r\n\r\n\t\t\t\r\n\t\t\tlet message_successIcon = controls_data('successicon') || '';\r\n\t\t\tlet message_errorIcon = controls_data('erroricon') || '';\r\n\t\t\tlet message_editSwitch = controls_data('editswitchopen') === 'yes' ? true : false;\r\n\t\t\tlet message_proClass = controls_data('editswitchopen') === 'yes' ? 'mf_pro_activated' : '';\r\n\t\t\t\r\n\t\t\tlet is_dummy_markup = is_edit_mode && message_editSwitch ? true : false;\r\n\r\n\t\t\t\r\n\t\t\treturn html`\r\n\t\t\t\t<form\r\n\t\t\t\t\tclassName=\"metform-form-content\"\r\n\t\t\t\t\tref=${parent.formContainerRef}\r\n\t\t\t\t\tonSubmit=${ validation.handleSubmit( parent.handleFormSubmit ) }\r\n\t\t\t\t\r\n\t\t\t\t\t>\r\n\t\t\t\r\n\t\t\t\r\n\t\t\t\t\t${is_dummy_markup ? message_position === 'top' ?  props.ResponseDummyMarkup(message_successIcon, message_proClass) : '' : ''}\r\n\t\t\t\t\t${is_dummy_markup ? ' ' :  message_position === 'top' ? props.SubmitResponseMarkup`${parent}${state}${message_successIcon}${message_errorIcon}${message_proClass}` : ''}\r\n\r\n\t\t\t\t\t<!--------------------------------------------------------\r\n\t\t\t\t\t*** IMPORTANT \/ DANGEROUS ***\r\n\t\t\t\t\t${html``} must be used as in immediate child of \"metform-form-main-wrapper\"\r\n\t\t\t\t\tclass otherwise multistep form will not run at all\r\n\t\t\t\t\t---------------------------------------------------------->\r\n\r\n\t\t\t\t\t<div className=\"metform-form-main-wrapper\" key=${'hide-form-after-submit'} ref=${parent.formRef}>\r\n\t\t\t\t\t${html`\r\n\t\t\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" key=\"2\" data-elementor-id=\"11722\" className=\"elementor elementor-11722\">\n\t\t\t\t<div className=\"elementor-element elementor-element-3ff73b4 e-con-full e-flex mk-enable-fade-animation-none mk-sticky-column-false mk-sticky-column-disable-tablet e-con e-parent\" data-id=\"3ff73b4\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;mk-animation-effect&quot;:&quot;none&quot;,&quot;mk_ext_is_sticky&quot;:&quot;false&quot;}\">\n\t\t<div className=\"elementor-element elementor-element-6f795d05 e-con-full e-flex mk-enable-fade-animation-none mk-sticky-column-false mk-sticky-column-disable-tablet e-con e-child\" data-id=\"6f795d05\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;mk-animation-effect&quot;:&quot;none&quot;,&quot;mk_ext_is_sticky&quot;:&quot;false&quot;}\">\n\t\t\t\t<div className=\"elementor-element elementor-element-1476e765 mk-enable-fade-animation-none elementor-widget elementor-widget-heading\" data-id=\"1476e765\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mk-animation-effect&quot;:&quot;none&quot;,&quot;mk_ext_is_infinite&quot;:&quot;false&quot;,&quot;mk_ext_is_scrollme&quot;:&quot;false&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 className=\"elementor-heading-title elementor-size-default\">Get Free Creative Consultation<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div className=\"elementor-element elementor-element-51fe805a mk-enable-fade-animation-none elementor-widget elementor-widget-heading\" data-id=\"51fe805a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mk-animation-effect&quot;:&quot;none&quot;,&quot;mk_ext_is_infinite&quot;:&quot;false&quot;,&quot;mk_ext_is_scrollme&quot;:&quot;false&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p className=\"elementor-heading-title elementor-size-default\">Share your details. Our team will connect shortly.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div className=\"elementor-element elementor-element-5da36d8e e-grid e-con-full mk-enable-fade-animation-none mk-sticky-column-false mk-sticky-column-disable-tablet e-con e-child\" data-id=\"5da36d8e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;mk-animation-effect&quot;:&quot;none&quot;,&quot;mk_ext_is_sticky&quot;:&quot;false&quot;}\">\n\t\t\t\t<div className=\"elementor-element elementor-element-70598782 mk-enable-fade-animation-none elementor-widget elementor-widget-mf-text\" data-id=\"70598782\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mf_input_name&quot;:&quot;Name&quot;,&quot;mk-animation-effect&quot;:&quot;none&quot;,&quot;mk_ext_is_infinite&quot;:&quot;false&quot;,&quot;mk_ext_is_scrollme&quot;:&quot;false&quot;}\" data-widget_type=\"mf-text.default\">\n\t\t\t\t\t\r\n\t\t<div className=\"mf-input-wrapper\">\r\n\t\t\t\r\n\t\t\t<input\r\n\t\t\t\ttype=\"text\"\r\n\t\t\t\tclassName=\"mf-input mf-conditional-input\"\r\n\t\t\t\tid=\"mf-input-text-70598782\"\r\n\t\t\t\tname=\"Name\"\r\n\t\t\t\tplaceholder=\"${ parent.decodeEntities(`Name`) } \"\r\n\t\t\t\t\t\t\t\t\tonInput=${parent.handleChange}\r\n\t\t\t\t\tonBlur=${parent.handleChange}\r\n\t\t\t\t\taria-invalid=${validation.errors['Name'] ? 'true' : 'false'}\r\n\t\t\t\t\tref=${el =>{\r\n\t\t\t\t\t\t\t\t\t\t\t\tparent.activateValidation({\"message\":\"This field is required.\",\"minLength\":1,\"maxLength\":\"\",\"type\":\"none\",\"required\":true,\"expression\":\"null\"}, el)\r\n\t\t\t\t\t}}\r\n\t\t\t\t\t\t\t\t\/>\r\n\r\n\t\t\t\t\t\t\t<${validation.ErrorMessage}\r\n\t\t\t\t\terrors=${validation.errors}\r\n\t\t\t\t\tname=\"Name\"\r\n\t\t\t\t\tas=${html`<span className=\"mf-error-message\"><\/span>`}\r\n\t\t\t\t\t\/>\r\n\t\t\t\r\n\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div className=\"elementor-element elementor-element-a06d9ee mk-enable-fade-animation-none elementor-widget elementor-widget-mf-telephone\" data-id=\"a06d9ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mf_input_name&quot;:&quot;Phone&quot;,&quot;mk-animation-effect&quot;:&quot;none&quot;,&quot;mk_ext_is_infinite&quot;:&quot;false&quot;,&quot;mk_ext_is_scrollme&quot;:&quot;false&quot;}\" data-widget_type=\"mf-telephone.default\">\n\t\t\t\t\t\n\t\t<div className=\"mf-input-wrapper\">\n\t\t\t\n\t\t\t<input\n\t\t\t\ttype=\"tel\"\n\t\t\t\tclassName=\"mf-input mf-conditional-input\"\n\t\t\t\tid=\"mf-input-telephone-a06d9ee\" \n\t\t\t\tname=\"Phone\"\n\t\t\t\tplaceholder=\"${ parent.decodeEntities(`Phone`) } \"\n\t\t\t\t\t\t\t\t\tonInput=${parent.handleChange}\n\t\t\t\t\taria-invalid=${validation.errors['Phone'] ? 'true' : 'false'}\n\t\t\t\t\tref=${el => parent.activateValidation({\"message\":\"This field is required.\",\"minLength\":1,\"maxLength\":\"\",\"type\":\"none\",\"required\":true,\"expression\":\"null\"}, el)}\n\t\t\t\t\t\t\t\t\/>\n\t\t\t\n\t\t\t\t\t\t\t<${validation.ErrorMessage}\n\t\t\t\t\terrors=${validation.errors}\n\t\t\t\t\tname=\"Phone\"\n\t\t\t\t\tas=${html`<span className=\"mf-error-message\"><\/span>`}\n\t\t\t\t\t\/>\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div className=\"elementor-element elementor-element-5fd1ec38 mk-enable-fade-animation-none elementor-widget elementor-widget-mf-email\" data-id=\"5fd1ec38\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mf_input_name&quot;:&quot;Email&quot;,&quot;mk-animation-effect&quot;:&quot;none&quot;,&quot;mk_ext_is_infinite&quot;:&quot;false&quot;,&quot;mk_ext_is_scrollme&quot;:&quot;false&quot;}\" data-widget_type=\"mf-email.default\">\n\t\t\t\t\t\r\n\t\t<div className=\"mf-input-wrapper\">\r\n\t\t\t\r\n\t\t\t<input \r\n\t\t\t\ttype=\"email\" \r\n\t\t\t\t \r\n\t\t\t\tdefaultValue=\"\" \r\n\t\t\t\tclassName=\"mf-input mf-conditional-input\" \r\n\t\t\t\tid=\"mf-input-email-5fd1ec38\" \r\n\t\t\t\tname=\"Email\" \r\n\t\t\t\tplaceholder=\"${ parent.decodeEntities(`Email`) } \" \r\n\t\t\t\t \r\n\t\t\t\tonBlur=${parent.handleChange} onFocus=${parent.handleChange} aria-invalid=${validation.errors['Email'] ? 'true' : 'false' } \r\n\t\t\t\tref=${el=> parent.activateValidation({\"message\":\"This field is required.\",\"emailMessage\":\"Please enter a valid Email address\",\"minLength\":1,\"maxLength\":\"\",\"type\":\"none\",\"required\":true,\"expression\":\"null\"}, el)}\r\n\t\t\t\t\t\t\t\/>\r\n\r\n\t\t\t\t\t\t<${validation.ErrorMessage} \r\n\t\t\t\terrors=${validation.errors} \r\n\t\t\t\tname=\"Email\" \r\n\t\t\t\tas=${html`<span className=\"mf-error-message\"><\/span>`}\r\n\t\t\t\/>\r\n\t\t\t\r\n\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t<\/div>\n\t\t\t\t<div className=\"elementor-element elementor-element-cc8b1fa mk-enable-fade-animation-none elementor-widget elementor-widget-mf-select\" data-id=\"cc8b1fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mf_input_name&quot;:&quot;Service&quot;,&quot;mf_input_list&quot;:[{&quot;mf_input_option_text&quot;:&quot;360 Marketing&quot;,&quot;mf_input_option_value&quot;:&quot;360 Marketing&quot;,&quot;_id&quot;:&quot;a277049&quot;,&quot;mf_input_option_status&quot;:&quot;&quot;,&quot;mf_input_option_selected&quot;:&quot;&quot;},{&quot;mf_input_option_text&quot;:&quot;Branding&quot;,&quot;mf_input_option_value&quot;:&quot;Branding&quot;,&quot;_id&quot;:&quot;58aba46&quot;,&quot;mf_input_option_status&quot;:&quot;&quot;,&quot;mf_input_option_selected&quot;:&quot;&quot;},{&quot;mf_input_option_text&quot;:&quot;Design&quot;,&quot;mf_input_option_value&quot;:&quot;Design&quot;,&quot;_id&quot;:&quot;1a42b7c&quot;,&quot;mf_input_option_status&quot;:&quot;&quot;,&quot;mf_input_option_selected&quot;:&quot;&quot;},{&quot;mf_input_option_text&quot;:&quot;Digital Marketing&quot;,&quot;mf_input_option_value&quot;:&quot;Digital Marketing&quot;,&quot;_id&quot;:&quot;c40e482&quot;,&quot;mf_input_option_status&quot;:&quot;&quot;,&quot;mf_input_option_selected&quot;:&quot;&quot;},{&quot;mf_input_option_text&quot;:&quot;Equipment Rental&quot;,&quot;mf_input_option_value&quot;:&quot;Equipment Rental&quot;,&quot;_id&quot;:&quot;30584d1&quot;,&quot;mf_input_option_status&quot;:&quot;&quot;,&quot;mf_input_option_selected&quot;:&quot;&quot;},{&quot;mf_input_option_text&quot;:&quot;Post Production&quot;,&quot;mf_input_option_value&quot;:&quot;Post Production&quot;,&quot;_id&quot;:&quot;0eb683f&quot;,&quot;mf_input_option_status&quot;:&quot;&quot;,&quot;mf_input_option_selected&quot;:&quot;&quot;},{&quot;mf_input_option_text&quot;:&quot;Product Photography&quot;,&quot;mf_input_option_value&quot;:&quot;Product Photography&quot;,&quot;_id&quot;:&quot;aaf2632&quot;,&quot;mf_input_option_status&quot;:&quot;&quot;,&quot;mf_input_option_selected&quot;:&quot;&quot;},{&quot;mf_input_option_text&quot;:&quot;Signages&quot;,&quot;mf_input_option_value&quot;:&quot;Signages&quot;,&quot;_id&quot;:&quot;763cc5a&quot;,&quot;mf_input_option_status&quot;:&quot;&quot;,&quot;mf_input_option_selected&quot;:&quot;&quot;},{&quot;mf_input_option_text&quot;:&quot;Social Media&quot;,&quot;mf_input_option_value&quot;:&quot;Social Media&quot;,&quot;_id&quot;:&quot;db98280&quot;,&quot;mf_input_option_status&quot;:&quot;&quot;,&quot;mf_input_option_selected&quot;:&quot;&quot;},{&quot;mf_input_option_text&quot;:&quot;Sync Sound&quot;,&quot;mf_input_option_value&quot;:&quot;Sync Sound&quot;,&quot;_id&quot;:&quot;925c3a7&quot;,&quot;mf_input_option_status&quot;:&quot;&quot;,&quot;mf_input_option_selected&quot;:&quot;&quot;},{&quot;mf_input_option_text&quot;:&quot;Video Production&quot;,&quot;mf_input_option_value&quot;:&quot;value-11&quot;,&quot;_id&quot;:&quot;510a60d&quot;,&quot;mf_input_option_status&quot;:&quot;&quot;,&quot;mf_input_option_selected&quot;:&quot;&quot;},{&quot;mf_input_option_text&quot;:&quot;Website&quot;,&quot;mf_input_option_value&quot;:&quot;Website&quot;,&quot;_id&quot;:&quot;e9d49c2&quot;,&quot;mf_input_option_status&quot;:&quot;&quot;,&quot;mf_input_option_selected&quot;:&quot;&quot;},{&quot;_id&quot;:&quot;d95cff2&quot;,&quot;mf_input_option_text&quot;:&quot;Digital Ads&quot;,&quot;mf_input_option_value&quot;:&quot;Digital Ads&quot;,&quot;mf_input_option_status&quot;:&quot;&quot;,&quot;mf_input_option_selected&quot;:&quot;&quot;},{&quot;_id&quot;:&quot;1343f9b&quot;,&quot;mf_input_option_text&quot;:&quot;AI Video Production&quot;,&quot;mf_input_option_value&quot;:&quot;AI Video Production&quot;,&quot;mf_input_option_status&quot;:&quot;&quot;,&quot;mf_input_option_selected&quot;:&quot;&quot;}],&quot;mk-animation-effect&quot;:&quot;none&quot;,&quot;mk_ext_is_infinite&quot;:&quot;false&quot;,&quot;mk_ext_is_scrollme&quot;:&quot;false&quot;}\" data-widget_type=\"mf-select.default\">\n\t\t\t\t\t\n\t\t\n\t\t<div className=\"mf-input-wrapper\">\n\t\t\t\n            <${props.Select}\n                className=${\"mf-input mf-input-select  \" + ( validation.errors['Service'] ? 'mf-invalid' : '' )}\n                classNamePrefix=\"mf_select\"\n                name=\"Service\"\n                placeholder=\"${ parent.decodeEntities(`Service`) } \"\n                isSearchable=${false}\n                options=${[{\"label\":\"360 Marketing\",\"value\":\"360 Marketing\",\"isDisabled\":false},{\"label\":\"Branding\",\"value\":\"Branding\",\"isDisabled\":false},{\"label\":\"Design\",\"value\":\"Design\",\"isDisabled\":false},{\"label\":\"Digital Marketing\",\"value\":\"Digital Marketing\",\"isDisabled\":false},{\"label\":\"Equipment Rental\",\"value\":\"Equipment Rental\",\"isDisabled\":false},{\"label\":\"Post Production\",\"value\":\"Post Production\",\"isDisabled\":false},{\"label\":\"Product Photography\",\"value\":\"Product Photography\",\"isDisabled\":false},{\"label\":\"Signages\",\"value\":\"Signages\",\"isDisabled\":false},{\"label\":\"Social Media\",\"value\":\"Social Media\",\"isDisabled\":false},{\"label\":\"Sync Sound\",\"value\":\"Sync Sound\",\"isDisabled\":false},{\"label\":\"Video Production\",\"value\":\"value-11\",\"isDisabled\":false},{\"label\":\"Website\",\"value\":\"Website\",\"isDisabled\":false},{\"label\":\"Digital Ads\",\"value\":\"Digital Ads\",\"isDisabled\":false},{\"label\":\"AI Video Production\",\"value\":\"AI Video Production\",\"isDisabled\":false}]}\n                value=${parent.getValue(\"Service\") ? [{\"label\":\"360 Marketing\",\"value\":\"360 Marketing\",\"isDisabled\":false},{\"label\":\"Branding\",\"value\":\"Branding\",\"isDisabled\":false},{\"label\":\"Design\",\"value\":\"Design\",\"isDisabled\":false},{\"label\":\"Digital Marketing\",\"value\":\"Digital Marketing\",\"isDisabled\":false},{\"label\":\"Equipment Rental\",\"value\":\"Equipment Rental\",\"isDisabled\":false},{\"label\":\"Post Production\",\"value\":\"Post Production\",\"isDisabled\":false},{\"label\":\"Product Photography\",\"value\":\"Product Photography\",\"isDisabled\":false},{\"label\":\"Signages\",\"value\":\"Signages\",\"isDisabled\":false},{\"label\":\"Social Media\",\"value\":\"Social Media\",\"isDisabled\":false},{\"label\":\"Sync Sound\",\"value\":\"Sync Sound\",\"isDisabled\":false},{\"label\":\"Video Production\",\"value\":\"value-11\",\"isDisabled\":false},{\"label\":\"Website\",\"value\":\"Website\",\"isDisabled\":false},{\"label\":\"Digital Ads\",\"value\":\"Digital Ads\",\"isDisabled\":false},{\"label\":\"AI Video Production\",\"value\":\"AI Video Production\",\"isDisabled\":false}].filter(item => item.value === parent.getValue(\"Service\"))[0] : []}\n                onChange=${(e)=> parent.handleSelect(e, \"Service\")}\n                ref=${() => {\n\t\t\t\t                    register({ name: \"Service\" }, parent.activateValidation({\"message\":\"This field is required.\",\"minLength\":1,\"maxLength\":\"\",\"type\":\"none\",\"required\":false}));\n                    if ( parent.getValue(\"Service\") === '' && false ) {\n\t\t\t\t    parent.setValue( 'Service', '', true );\n                        parent.handleChange({\n                            target: {\n                                name: 'Service',\n                                value: ''\n                            }\n                        });\n                    }\n                }}\n                \/>\n\n            \t\t\t\t<${validation.ErrorMessage}\n\t\t\t\t\terrors=${validation.errors}\n\t\t\t\t\tname=\"Service\"\n\t\t\t\t\tas=${html`<span className=\"mf-error-message\"><\/span>`}\n\t\t\t\t\t\/>\n\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div className=\"elementor-element elementor-element-1f8d3f6f elementor-widget__width-auto mk-enable-fade-animation-none elementor-widget elementor-widget-mf-button\" data-id=\"1f8d3f6f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mk-animation-effect&quot;:&quot;none&quot;,&quot;mk_ext_is_infinite&quot;:&quot;false&quot;,&quot;mk_ext_is_scrollme&quot;:&quot;false&quot;}\" data-widget_type=\"mf-button.default\">\n\t\t\t\t\t\t\t<div className=\"mf-btn-wraper mf-conditional-input\" data-mf-form-conditional-logic-requirement=\"\">\r\n\t\t\t\t\t\t\t<button type=\"submit\" className=\"metform-btn metform-submit-btn \" id=\"\">\r\n\t\t\t\t\t<span>${ parent.decodeEntities(`Send Request`) } <\/span>\r\n\t\t\t\t<\/button>\r\n\t\t\t        <\/div>\r\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t`}\r\n\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t${is_dummy_markup ? message_position === 'bottom' ? props.ResponseDummyMarkup(message_successIcon, message_proClass) : '' : ''}\r\n\t\t\t\t\t${is_dummy_markup ? ' ' : message_position === 'bottom' ? props.SubmitResponseMarkup`${parent}${state}${message_successIcon}${message_errorIcon}${message_proClass}` : ''}\r\n\t\t\t\t\r\n\t\t\t\t<\/form>\r\n\t\t\t`\r\n\t\t<\/script>\r\n\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-defbd40 e-con-full e-flex mk-enable-fade-animation-none mk-sticky-column-false mk-sticky-column-disable-tablet e-con e-parent\" data-id=\"defbd40\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;mk-animation-effect&quot;:&quot;none&quot;,&quot;mk_ext_is_sticky&quot;:&quot;false&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2798c5a mk-enable-fade-animation-none elementor-widget elementor-widget-google_maps\" data-id=\"2798c5a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mk-animation-effect&quot;:&quot;none&quot;,&quot;mk_ext_is_infinite&quot;:&quot;false&quot;,&quot;mk_ext_is_scrollme&quot;:&quot;false&quot;}\" data-widget_type=\"google_maps.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe loading=\"lazy\"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=Bandish%20studios&#038;t=m&#038;z=12&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\ttitle=\"Bandish studios\"\n\t\t\t\t\taria-label=\"Bandish studios\"\n\t\t\t><\/iframe>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>We Create Video Content That Grows Your Brand From brand films to social ads, we craft stories that connect with your audience and deliver results. Here&#8217;s what we have been creating! At Bandish, we believe every idea deserves a powerful [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-10049","page","type-page","status-publish","hentry"],"_hostinger_reach_plugin_has_subscription_block":false,"_hostinger_reach_plugin_is_elementor":false,"_links":{"self":[{"href":"https:\/\/bandishstudios.com\/landing\/wp-json\/wp\/v2\/pages\/10049","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bandishstudios.com\/landing\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/bandishstudios.com\/landing\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/bandishstudios.com\/landing\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bandishstudios.com\/landing\/wp-json\/wp\/v2\/comments?post=10049"}],"version-history":[{"count":190,"href":"https:\/\/bandishstudios.com\/landing\/wp-json\/wp\/v2\/pages\/10049\/revisions"}],"predecessor-version":[{"id":12119,"href":"https:\/\/bandishstudios.com\/landing\/wp-json\/wp\/v2\/pages\/10049\/revisions\/12119"}],"wp:attachment":[{"href":"https:\/\/bandishstudios.com\/landing\/wp-json\/wp\/v2\/media?parent=10049"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}